{"id":4804,"date":"2022-04-29T12:09:24","date_gmt":"2022-04-29T12:09:24","guid":{"rendered":"https:\/\/www.notijalapa.net\/noticias\/?p=4804"},"modified":"2022-04-29T12:21:17","modified_gmt":"2022-04-29T12:21:17","slug":"programan-los-juegos-deportivos-escolares","status":"publish","type":"post","link":"https:\/\/www.notijalapa.net\/noticias\/2022\/04\/29\/programan-los-juegos-deportivos-escolares\/","title":{"rendered":"Programan los juegos deportivos escolares"},"content":{"rendered":"<p>Ya est\u00e1n trabajando para que en las pr\u00f3ximas semanas se puedan realizar los juegos deportivos escolares, van a trabajar en una modalidad hibrida, van a tener una parte presencial y otra virtual, seg\u00fan lo dio a conocer Johann Aguirre encargado de la Oficina de Educaci\u00f3n F\u00edsica en Jalapa.<\/p>\n<p><a href=\"https:\/\/www.notijalapa.net\/noticias\/2022\/04\/29\/coes-municipales-intensificaran-su-trabajo-por-el-ingreso-del-invierno\/\">MIRA: COES municipales intensificaran su trabajo por el ingreso del invierno<\/a><\/p>\n<p>El desarrollo de las diferentes activades, la van a realizar en grupo peque\u00f1os, van a trabajar tambi\u00e9n habilidades motrices, de estas habilidades se van a grabar algunos videos que se van mandar a la ciudad capital, en donde dar\u00e1n una calificaci\u00f3n y ver quienes pueden ir al evento nacional que se va desarrollar en el departamento de Retalhuleu.<\/p>\n<p><iframe loading=\"lazy\" title=\"Programan Los Juegos Deportivos Escolares 1\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/eNsbXk-FN7M?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>Tienen varios d\u00edas para desarrollar estos juegos deportivos escolares, en donde esperan contar con el apoyo de los j\u00f3venes y ni\u00f1os de los diferentes centros educativos, para que Jalapa pueda participar en el evento nacional.<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2Fpermalink.php%3Fstory_fbid%3D5092813520834758%26id%3D541551329294356&amp;show_text=true&amp;width=500\" width=\"500\" height=\"812\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ya est\u00e1n trabajando para que en las pr\u00f3ximas semanas se puedan realizar los juegos deportivos escolares, van a trabajar en una modalidad hibrida, van a tener una parte presencial y otra virtual, seg\u00fan lo dio a conocer Johann Aguirre encargado de la Oficina de Educaci\u00f3n F\u00edsica en Jalapa. MIRA: COES municipales intensificaran su trabajo por el ingreso del invierno El desarrollo de las diferentes activades, la van a realizar en grupo peque\u00f1os, van a trabajar tambi\u00e9n habilidades motrices, de estas habilidades se van a grabar algunos videos que se van&hellip;<\/p>\n","protected":false},"author":2,"featured_media":4797,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[1133,1134],"class_list":["post-4804","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales","tag-juegos-deportivos-escolares","tag-programan"],"gutentor_comment":0,"_links":{"self":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts\/4804","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/comments?post=4804"}],"version-history":[{"count":2,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts\/4804\/revisions"}],"predecessor-version":[{"id":4816,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts\/4804\/revisions\/4816"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/media\/4797"}],"wp:attachment":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/media?parent=4804"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/categories?post=4804"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/tags?post=4804"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}