{"id":32759,"date":"2026-09-02T11:00:52","date_gmt":"2026-09-02T11:00:52","guid":{"rendered":"https:\/\/www.notijalapa.net\/noticias\/?p=32759"},"modified":"2026-09-02T11:16:49","modified_gmt":"2026-09-02T11:16:49","slug":"esta-semana-continuamos-con-ausencia-de-lluvias-y-dias-calurosos","status":"publish","type":"post","link":"https:\/\/www.notijalapa.net\/noticias\/2026\/09\/02\/esta-semana-continuamos-con-ausencia-de-lluvias-y-dias-calurosos\/","title":{"rendered":"Esta semana continuamos con ausencia de lluvias y d\u00edas calurosos"},"content":{"rendered":"<p>En cuanto a las condiciones clim\u00e1ticas que ha trasladado el insivumeh para esta semana, b\u00e1sicamente se resumen en que vamos a tener altas temperaturas y alta radiaci\u00f3n solar, seg\u00fan lo dio a conocer el Ing. Cristian Estrada delegado de la CONRED.<\/p>\n<p><a href=\"https:\/\/www.notijalapa.net\/noticias\/2026\/09\/02\/esperan-que-la-dideduc-brinde-instrucciones-para-el-tema-de-las-antorchas\/\">MIRA: Esperan que la DIDEDUC brinde instrucciones para el tema de las antorchas<\/a><\/p>\n<p>Esto tambi\u00e9n va a acompa\u00f1ado de condiciones locales y entrada de humedad tanto del pacifico como del atl\u00e1ntico, pero el d\u00eda lunes se tuvieron lluvias a nivel de costa, boca costa, altiplano central y b\u00e1sicamente para Jalapa no hubo precipitaci\u00f3n.<\/p>\n<p><iframe loading=\"lazy\" title=\"Esta semana continuamos con ausencia de lluvias y d\u00edas calurosos\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/KRZCcvwN9ZM?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>Este es un problema porque ya empez\u00f3 a llover en otros lugares y Jalapa se ha quedado sin lluvia al igual que otros departamentos, estas son las condiciones clim\u00e1ticas que van a prevalecer durante esta semana.<\/p>\n<p>A partir del 15 de septiembre estar\u00eda ingresando la segunda etapa del invierno, esperan que, para la pr\u00f3xima semana ya los pron\u00f3sticos cambien y se empiece a tener lluvias considerables en el departamento de Jalapa.<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2Fpermalink.php%3Fstory_fbid%3Dpfbid02LS7VNHaGYPU4LahniFVMZdfTFbuAUYWwbStL41sDsEd44rftWQwRHXWw9vs76upEl%26id%3D100083158940816&amp;show_text=true&amp;width=500\" width=\"500\" height=\"544\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En cuanto a las condiciones clim\u00e1ticas que ha trasladado el insivumeh para esta semana, b\u00e1sicamente se resumen en que vamos a tener altas temperaturas y alta radiaci\u00f3n solar, seg\u00fan lo dio a conocer el Ing. Cristian Estrada delegado de la CONRED. MIRA: Esperan que la DIDEDUC brinde instrucciones para el tema de las antorchas Esto tambi\u00e9n va a acompa\u00f1ado de condiciones locales y entrada de humedad tanto del pacifico como del atl\u00e1ntico, pero el d\u00eda lunes se tuvieron lluvias a nivel de costa, boca costa, altiplano central y b\u00e1sicamente para&hellip;<\/p>\n","protected":false},"author":2,"featured_media":32752,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[12658,12657],"class_list":["post-32759","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales","tag-de-lluvias-y-dias-calurosos","tag-esta-semana-continuamos-con-ausencia"],"gutentor_comment":0,"_links":{"self":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts\/32759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/comments?post=32759"}],"version-history":[{"count":2,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts\/32759\/revisions"}],"predecessor-version":[{"id":32769,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts\/32759\/revisions\/32769"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/media\/32752"}],"wp:attachment":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/media?parent=32759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/categories?post=32759"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/tags?post=32759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}