{"id":30853,"date":"2026-05-09T12:48:53","date_gmt":"2026-05-09T12:48:53","guid":{"rendered":"https:\/\/www.notijalapa.net\/noticias\/?p=30853"},"modified":"2026-05-09T12:48:53","modified_gmt":"2026-05-09T12:48:53","slug":"unas-1500-personas-han-certificado-por-hacer-bien-su-oficio","status":"publish","type":"post","link":"https:\/\/www.notijalapa.net\/noticias\/2026\/05\/09\/unas-1500-personas-han-certificado-por-hacer-bien-su-oficio\/","title":{"rendered":"Unas 1,500 personas han certificado por hacer bien su oficio"},"content":{"rendered":"<p>Desde que iniciaron con este programa han realizado certificaciones en todo el departamento de Jalapa, han hecho certificaciones en coordinaci\u00f3n con municipalidades, para capacitar al personal en atenci\u00f3n al cliente, ese oficio es bastante bonito y satisfactorio para las personas de las municipalidades, porque es all\u00ed donde est\u00e1n dando a conocer la entrega y el servicio a su pueblo, seg\u00fan lo dio a conocer la Licda. Ligia Mart\u00ednez encargada de DIGEEX<\/p>\n<p>Tambi\u00e9n han realizado certificaciones a personas que trabajan en el \u00e1rea de caficultura y otros oficios de personas que trabajan tanto en las municipalidades como en diferentes sectores del departamento de Jalapa esto reconociendo la experiencia y la labor que cada una de estas personas pueda tener.<\/p>\n<p>Desde que iniciaron en el departamento de Jalapa con este programa, han certificado a unas 1,500 personas en diferentes profesiones u oficios. Para poder inscribirse y obtener esta certificaci\u00f3n, pueden acudir a la direcci\u00f3n departamental de educaci\u00f3n en la oficina de coordinaci\u00f3n departamental de educaci\u00f3n extraescolar, posteriormente deber\u00e1n esperar las fechas de las diferentes jornadas que se realizar\u00e1n y los grupos deben de ser no menores de 15 personas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde que iniciaron con este programa han realizado certificaciones en todo el departamento de Jalapa, han hecho certificaciones en coordinaci\u00f3n con municipalidades, para capacitar al personal en atenci\u00f3n al cliente, ese oficio es bastante bonito y satisfactorio para las personas de las municipalidades, porque es all\u00ed donde est\u00e1n dando a conocer la entrega y el servicio a su pueblo, seg\u00fan lo dio a conocer la Licda. Ligia Mart\u00ednez encargada de DIGEEX Tambi\u00e9n han realizado certificaciones a personas que trabajan en el \u00e1rea de caficultura y otros oficios de personas que&hellip;<\/p>\n","protected":false},"author":2,"featured_media":30844,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[11775,11776,11774],"class_list":["post-30853","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales","tag-500-personas-han-certificado","tag-por-hacer-bien-su-oficio","tag-unas-1"],"gutentor_comment":0,"_links":{"self":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts\/30853","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/comments?post=30853"}],"version-history":[{"count":1,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts\/30853\/revisions"}],"predecessor-version":[{"id":30854,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts\/30853\/revisions\/30854"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/media\/30844"}],"wp:attachment":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/media?parent=30853"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/categories?post=30853"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/tags?post=30853"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}