{"id":24763,"date":"2025-05-02T13:01:16","date_gmt":"2025-05-02T13:01:16","guid":{"rendered":"https:\/\/www.notijalapa.net\/noticias\/?p=24763"},"modified":"2025-05-02T13:19:20","modified_gmt":"2025-05-02T13:19:20","slug":"jalapanecos-se-ponen-en-riesgo-por-la-inaccion-de-la-pnc","status":"publish","type":"post","link":"https:\/\/www.notijalapa.net\/noticias\/2025\/05\/02\/jalapanecos-se-ponen-en-riesgo-por-la-inaccion-de-la-pnc\/","title":{"rendered":"Jalapanecos se ponen en riesgo por la inacci\u00f3n de la PNC"},"content":{"rendered":"<p>Se pone en riesgo la seguridad de los jalapanecos por la inacci\u00f3n de la Polic\u00eda Nacional Civil, considerando que legalmente esta facultad de capturar ladrones o criminales le corresponde a la PNC, seg\u00fan lo manifest\u00f3 la Licda. Cecilia Isabel Aguirre Auxiliar del Procurador de los Derechos Humanos.<\/p>\n<p><a href=\"https:\/\/www.notijalapa.net\/noticias\/2025\/05\/02\/buscan-atraer-el-turismo-con-una-media-maraton\/\">MIRA: Buscan atraer el turismo con una media marat\u00f3n<\/a><\/p>\n<p>No se debe poner en riesgo a los ciudadanos que en alguna manera cansados de todo lo que est\u00e1 sucediendo, quieren poner la justicia por sus propias manos, considera que no es oportuno y la seguridad le corresponde a Polic\u00eda Nacional Civil, para que los ciudadanos no se pongan en riesgo.<\/p>\n<p><iframe loading=\"lazy\" title=\"Jalapanecos se ponen en riesgo por la inacci\u00f3n de la PNC\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/i6pg3OGkLbc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>Es la inacci\u00f3n, la falta de proyectos, el tema de prevenci\u00f3n, atenci\u00f3n, muchas veces las personas llaman a la PNC para ser atendidas y dos o tres horas despu\u00e9s no hay una respuesta y es reacci\u00f3n de cansancio que la poblaci\u00f3n tiene en las respuestas que ellos esperan en materia de seguridad.<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2Fpermalink.php%3Fstory_fbid%3Dpfbid0yJ4eZSmVSLHUbcnqy2SfW4PghEcQDkunhLsNPKCcpqmuR72zU6E86dsQEC3d2A8Ll%26id%3D100083158940816&amp;show_text=true&amp;width=500\" width=\"500\" height=\"545\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se pone en riesgo la seguridad de los jalapanecos por la inacci\u00f3n de la Polic\u00eda Nacional Civil, considerando que legalmente esta facultad de capturar ladrones o criminales le corresponde a la PNC, seg\u00fan lo manifest\u00f3 la Licda. Cecilia Isabel Aguirre Auxiliar del Procurador de los Derechos Humanos. MIRA: Buscan atraer el turismo con una media marat\u00f3n No se debe poner en riesgo a los ciudadanos que en alguna manera cansados de todo lo que est\u00e1 sucediendo, quieren poner la justicia por sus propias manos, considera que no es oportuno y&hellip;<\/p>\n","protected":false},"author":2,"featured_media":24755,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[9009,9010],"class_list":["post-24763","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales","tag-jalapanecos-se-ponen-en-riesgo","tag-por-la-inaccion-de-la-pnc"],"gutentor_comment":0,"_links":{"self":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts\/24763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/comments?post=24763"}],"version-history":[{"count":2,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts\/24763\/revisions"}],"predecessor-version":[{"id":24772,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts\/24763\/revisions\/24772"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/media\/24755"}],"wp:attachment":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/media?parent=24763"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/categories?post=24763"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/tags?post=24763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}