{"id":24759,"date":"2025-05-02T13:00:11","date_gmt":"2025-05-02T13:00:11","guid":{"rendered":"https:\/\/www.notijalapa.net\/noticias\/?p=24759"},"modified":"2025-05-02T13:21:08","modified_gmt":"2025-05-02T13:21:08","slug":"la-violencia-se-incrementa-en-jalapa-por-falta-de-seguridad","status":"publish","type":"post","link":"https:\/\/www.notijalapa.net\/noticias\/2025\/05\/02\/la-violencia-se-incrementa-en-jalapa-por-falta-de-seguridad\/","title":{"rendered":"La violencia se incrementa en Jalapa por falta de seguridad"},"content":{"rendered":"<p>Se sienten altamente preocupados por el derecho a la vida en el departamento de Jalapa, y se refiere a este derecho en tanto que, los hechos de violencia que se han incrementado vulneran el derecho a la vida de las mujeres y hombres, seg\u00fan lo dio a conocer la Licda. Cecilia Isabel Aguirre Auxiliar del Procurador de los Derechos Humanos.<\/p>\n<p><a href=\"https:\/\/www.notijalapa.net\/noticias\/2025\/05\/02\/incendios-atendidos-por-bomberos-voluntarios\/\">MIRA: Incendios atendidos por Bomberos Voluntarios<\/a><\/p>\n<p>Dentro de la supervisi\u00f3n que en materia de derechos humanos ellos realizan, es importante dar a conocer que tienen resultados sobre las debilidades en el sistema de seguridad en el departamento de Jalapa y sobre todo desde gobernaci\u00f3n y la comisaria de PNC.<\/p>\n<p><iframe loading=\"lazy\" title=\"La violencia se incrementa en Jalapa por falta de seguridad\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/qVtpfbge62c?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>Eso quiere decir que, un agente de PNC tiene que resguardar a m\u00e1s de mil ciudadanos jalapanecos, esto es algo imposible, se necesita una buena infraestructura, veh\u00edculos, equipo necesario para que los agente realicen un trabajo honorable y digno a favor de los jalapanecos que de momento no se tiene.<\/p>\n<p>Es por ello que, los planes y proyectos en materia de seguridad y de prevenci\u00f3n deben de ser bien desarrollados y estrat\u00e9gicamente de acuerdo al departamento de Jalapa y que deben de ser emanados desde la gobernaci\u00f3n departamental hacia la PNC desde una estrategia de pa\u00eds.<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2Fpermalink.php%3Fstory_fbid%3Dpfbid02271H94ULQQGemRPWJXUmJy65pKMbrWiZGGsv12Eq1Z51boZKHYyYQjsxTz1wcnXWl%26id%3D100083158940816&amp;show_text=true&amp;width=500\" width=\"500\" height=\"774\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se sienten altamente preocupados por el derecho a la vida en el departamento de Jalapa, y se refiere a este derecho en tanto que, los hechos de violencia que se han incrementado vulneran el derecho a la vida de las mujeres y hombres, seg\u00fan lo dio a conocer la Licda. Cecilia Isabel Aguirre Auxiliar del Procurador de los Derechos Humanos. MIRA: Incendios atendidos por Bomberos Voluntarios Dentro de la supervisi\u00f3n que en materia de derechos humanos ellos realizan, es importante dar a conocer que tienen resultados sobre las debilidades en&hellip;<\/p>\n","protected":false},"author":2,"featured_media":24755,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[9005,9006],"class_list":["post-24759","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales","tag-la-violencia-se-incrementa-en-jalapa","tag-por-falta-de-seguridad"],"gutentor_comment":0,"_links":{"self":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts\/24759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/comments?post=24759"}],"version-history":[{"count":2,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts\/24759\/revisions"}],"predecessor-version":[{"id":24774,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts\/24759\/revisions\/24774"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/media\/24755"}],"wp:attachment":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/media?parent=24759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/categories?post=24759"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/tags?post=24759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}