{"id":2433,"date":"2022-01-07T11:41:14","date_gmt":"2022-01-07T11:41:14","guid":{"rendered":"https:\/\/www.notijalapa.net\/noticias\/?p=2433"},"modified":"2022-01-07T11:41:14","modified_gmt":"2022-01-07T11:41:14","slug":"82-proyectos-se-realizaran-este-ano-con-fondos-de-codede","status":"publish","type":"post","link":"https:\/\/www.notijalapa.net\/noticias\/2022\/01\/07\/82-proyectos-se-realizaran-este-ano-con-fondos-de-codede\/","title":{"rendered":"82 proyectos se realizar\u00e1n este a\u00f1o con fondos de CODEDE"},"content":{"rendered":"<p>En la ejecuci\u00f3n del presupuesto de los Consejos de Desarrollo, el a\u00f1o pasado finalizado en cuarto lugar a nivel nacional, quedando pendientes unos proyectos de gran magnitud que no se pudieron concluir en un cien por ciento, seg\u00fan lo dio a conocer Jorge Cortez Gobernador Departamental de Jalapa.<\/p>\n<p>Para este a\u00f1o hay un aumento en el presupuesto, son aproximadamente 87 millones los que vienen destinados para todo el departamento de Jalapa, con los que se van a realizar 82 proyectos.<\/p>\n<p>Esperan ejecutar un cien por ciento del presupuesto y que no queden obras de arrastre para el pr\u00f3ximo a\u00f1o, esto con el apoyo de las direcciones municipales de planificaci\u00f3n, los alcaldes y los Consejos de Desarrollo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la ejecuci\u00f3n del presupuesto de los Consejos de Desarrollo, el a\u00f1o pasado finalizado en cuarto lugar a nivel nacional, quedando pendientes unos proyectos de gran magnitud que no se pudieron concluir en un cien por ciento, seg\u00fan lo dio a conocer Jorge Cortez Gobernador Departamental de Jalapa. Para este a\u00f1o hay un aumento en el presupuesto, son aproximadamente 87 millones los que vienen destinados para todo el departamento de Jalapa, con los que se van a realizar 82 proyectos. Esperan ejecutar un cien por ciento del presupuesto y que&hellip;<\/p>\n","protected":false},"author":2,"featured_media":2427,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[465,93],"class_list":["post-2433","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales","tag-82-proyectos","tag-consejos-de-desarrollo"],"gutentor_comment":0,"_links":{"self":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts\/2433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/comments?post=2433"}],"version-history":[{"count":1,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts\/2433\/revisions"}],"predecessor-version":[{"id":2434,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts\/2433\/revisions\/2434"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/media\/2427"}],"wp:attachment":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/media?parent=2433"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/categories?post=2433"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/tags?post=2433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}