{"id":23647,"date":"2025-02-22T13:15:40","date_gmt":"2025-02-22T13:15:40","guid":{"rendered":"https:\/\/www.notijalapa.net\/noticias\/?p=23647"},"modified":"2025-02-22T13:31:56","modified_gmt":"2025-02-22T13:31:56","slug":"dos-accidentes-ocurridos-en-las-ultimas-24-horas","status":"publish","type":"post","link":"https:\/\/www.notijalapa.net\/noticias\/2025\/02\/22\/dos-accidentes-ocurridos-en-las-ultimas-24-horas\/","title":{"rendered":"Dos accidentes ocurridos en las \u00faltimas 24 horas"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>Los socorristas destacaron sus unidades al barrio Chipilapa, en donde les informaron sobre un accidente de tr\u00e1nsito, al llegar al lugar constataron que se trataba de una persona atropellada, atendiendo a una persona de sexo masculino que no fue identificado, de aproximadamente 45 a\u00f1os, presentando trauma de cr\u00e1neo, golpes y laceraciones en distintas partes del cuerpo, seg\u00fan lo dio a conocer Benfer Arana portavoz de Bomberos Voluntarios.<\/p>\n<p><a href=\"https:\/\/www.notijalapa.net\/noticias\/2025\/02\/22\/con-la-eleccion-de-la-madrina-de-bomberos-voluntarios-inician-las-actividades-de-aniversario\/\">MIRA: Con la elecci\u00f3n de la madrina de Bomberos Voluntarios inician las actividades de aniversario<\/a><\/p>\n<p>El paciente fue estabilizado en el lugar y posteriormente trasladado en estado inconsciente a la emergencia del hospital nacional de Jalapa para su tratamiento respectivo por los m\u00e9dicos de turno.<\/p>\n<p><iframe loading=\"lazy\" title=\"Dos accidentes ocurridos en las \u00faltimas 24 horas\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/3_v2QHIFzcI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>As\u00ed mismo, han movilizado muchas unidades a la 6ta avenida, entre 5ta y 6ta calle, en la zona 2 del barrio San Francisco, en donde atendieron a Jeisson Alfredo Ruedas Cruz; de 24 a\u00f1os, esta persona sufri\u00f3 un accidente de motorista, presentando posible fractura de la r\u00f3tula derecha, posible fractura de pelvis derecha, golpes y abrasiones en distintas partes del cuerpo.<\/p>\n<p>Mismas que se ocasion\u00f3 cuando se conduc\u00eda en una motocicleta de caracter\u00edsticas desconocidas y por causas que se desconocen colisionara con una moto taxi. El paciente fue estabilizado en el lugar y posteriormente trasladado a la emergencia del centro asistencial para que fuera evaluado por los m\u00e9dicos de turno.<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2Fpermalink.php%3Fstory_fbid%3Dpfbid0bSeBwze7wsaTPaEGip8MtJ79qMnPqN7TWn6g3aDoW4ieVU7M1h8YmFDpRVR9iynnl%26id%3D100083158940816&amp;show_text=true&amp;width=500\" width=\"500\" height=\"813\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Los socorristas destacaron sus unidades al barrio Chipilapa, en donde les informaron sobre un accidente de tr\u00e1nsito, al llegar al lugar constataron que se trataba de una persona atropellada, atendiendo a una persona de sexo masculino que no fue identificado, de aproximadamente 45 a\u00f1os, presentando trauma de cr\u00e1neo, golpes y laceraciones en distintas partes del cuerpo, seg\u00fan lo dio a conocer Benfer Arana portavoz de Bomberos Voluntarios. MIRA: Con la elecci\u00f3n de la madrina de Bomberos Voluntarios inician las actividades de aniversario El paciente fue estabilizado en el lugar&hellip;<\/p>\n","protected":false},"author":2,"featured_media":23633,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[7914,3039],"class_list":["post-23647","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales","tag-dos-accidentes-ocurridos","tag-en-las-ultimas-24-horas"],"gutentor_comment":0,"_links":{"self":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts\/23647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/comments?post=23647"}],"version-history":[{"count":3,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts\/23647\/revisions"}],"predecessor-version":[{"id":23650,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts\/23647\/revisions\/23650"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/media\/23633"}],"wp:attachment":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/media?parent=23647"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/categories?post=23647"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/tags?post=23647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}