{"id":2332,"date":"2021-12-31T12:22:48","date_gmt":"2021-12-31T12:22:48","guid":{"rendered":"https:\/\/www.notijalapa.net\/noticias\/?p=2332"},"modified":"2021-12-31T12:39:13","modified_gmt":"2021-12-31T12:39:13","slug":"participa-en-la-tradicional-carrera-san-silvestre","status":"publish","type":"post","link":"https:\/\/www.notijalapa.net\/noticias\/2021\/12\/31\/participa-en-la-tradicional-carrera-san-silvestre\/","title":{"rendered":"Participa en la tradicional carrera San Silvestre"},"content":{"rendered":"<p>Ya est\u00e1n preparados para realizar la tradicional carrera San Silvestre en Jalapa, en donde esperan puedan tener mucha m\u00e1s afluencia de personas ya que se est\u00e1n preparando para que este \u00faltimo d\u00eda del a\u00f1o sea una fiesta desde las primeras horas del d\u00eda, siempre tomando las medidas de prevenci\u00f3n sobre el Covid-19, seg\u00fan lo dio a conocer Fernando Ju\u00e1rez quien es parte del comit\u00e9 organizador.<\/p>\n<p><a href=\"https:\/\/www.notijalapa.net\/noticias\/2021\/12\/31\/lo-capturan-por-portar-un-arma-de-fuego-con-reporte-de-robo\/\">MIRA: Lo capturan por portar un arma de fuego con reporte de robo<\/a><\/p>\n<p>Se van a tener varias categor\u00edas, esto tambi\u00e9n gracias al se\u00f1or Manolo Morataya, quien es el que ha tomado la iniciativa de que a\u00f1o con a\u00f1o se realice esta carrera y los primeros tres lugares tienen trofeos, diplomas y premios en efectivo.<\/p>\n<p><iframe loading=\"lazy\" title=\"Participa En La Tradicional Carrera San Silvestre 1\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/lLvk_Ib_jPc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>Hace la invitaci\u00f3n a todas las personas para que participen en esta tradicional carrera San Silvestre, para que puedan culminar el a\u00f1o 2021 corriendo y que no se pierda esta tradicional carrera en Jalapa. La inscripci\u00f3n es gratis y tendr\u00e1n diferentes premios.<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2Fpermalink.php%3Fstory_fbid%3D4729917437124370%26id%3D541551329294356&amp;show_text=true&amp;width=500\" width=\"500\" height=\"754\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ya est\u00e1n preparados para realizar la tradicional carrera San Silvestre en Jalapa, en donde esperan puedan tener mucha m\u00e1s afluencia de personas ya que se est\u00e1n preparando para que este \u00faltimo d\u00eda del a\u00f1o sea una fiesta desde las primeras horas del d\u00eda, siempre tomando las medidas de prevenci\u00f3n sobre el Covid-19, seg\u00fan lo dio a conocer Fernando Ju\u00e1rez quien es parte del comit\u00e9 organizador. MIRA: Lo capturan por portar un arma de fuego con reporte de robo Se van a tener varias categor\u00edas, esto tambi\u00e9n gracias al se\u00f1or Manolo&hellip;<\/p>\n","protected":false},"author":2,"featured_media":2333,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[440,441],"class_list":["post-2332","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales","tag-san-silvestre-en-jalapa","tag-ultimo-dia-del-ano"],"gutentor_comment":0,"_links":{"self":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts\/2332","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/comments?post=2332"}],"version-history":[{"count":2,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts\/2332\/revisions"}],"predecessor-version":[{"id":2347,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts\/2332\/revisions\/2347"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/media\/2333"}],"wp:attachment":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/media?parent=2332"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/categories?post=2332"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/tags?post=2332"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}