{"id":22246,"date":"2024-11-29T10:57:51","date_gmt":"2024-11-29T10:57:51","guid":{"rendered":"https:\/\/www.notijalapa.net\/noticias\/?p=22246"},"modified":"2024-11-29T11:16:35","modified_gmt":"2024-11-29T11:16:35","slug":"tiene-hasta-este-viernes-para-la-revision-de-los-documentos-de-proyectos-2024","status":"publish","type":"post","link":"https:\/\/www.notijalapa.net\/noticias\/2024\/11\/29\/tiene-hasta-este-viernes-para-la-revision-de-los-documentos-de-proyectos-2024\/","title":{"rendered":"Tiene hasta este viernes para la revisi\u00f3n de los documentos de proyectos 2024"},"content":{"rendered":"<p>Para los proyectos 2024 el plazo para presentar informaci\u00f3n en la delegaci\u00f3n departamental de SEGEPLAN se venci\u00f3 el 15 de noviembre, en este momento despu\u00e9s de esta fecha hasta el 29 de ese mismo mes tienen el tiempo para la revisi\u00f3n de la documentaci\u00f3n, seg\u00fan el Ing. Manuel C\u00e1rcamo delegado interino de SEGEPLAN.<\/p>\n<p><a href=\"https:\/\/www.notijalapa.net\/noticias\/2024\/11\/29\/presentan-la-2da-edicion-de-la-revista-informatica-sobre-el-empleo-y-desempleo\/\">MIRA: Presentan la 2da. edici\u00f3n de la revista inform\u00e1tica sobre el empleo y desempleo<\/a><\/p>\n<p>El sistema se cierra este viernes, ya que es el \u00faltimo d\u00eda h\u00e1bil del mes de noviembre, posterior a esta fecha deben esperar instrucciones del consejo nacional de desarrollo urbano y rural para saber cual ser\u00e1 el proceso si es que alg\u00fan proyecto no llegara a cumplir con toda la documentaci\u00f3n respectiva.<\/p>\n<p><iframe loading=\"lazy\" title=\"Tiene hasta este viernes para la revisi\u00f3n de los documentos de proyectos 2024\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/01NuwbPHlCQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>Los proyectos corresponden al ejercicio fiscal 2024, aunque en el congreso se aprob\u00f3 una ley en donde no va a quedar ning\u00fan proyecto de arrastre y el a\u00f1o 2025 van a iniciar con el presupuesto nuevo que fue aprobado hace unos d\u00edas.<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2Fpermalink.php%3Fstory_fbid%3Dpfbid0FLzd7M59b2zSeqWuj9bFVqPTmkh3a6jPwRqgpFzpgwLCrw166Jh1GeErNyF52HVel%26id%3D100083158940816&amp;show_text=true&amp;width=500\" width=\"500\" height=\"525\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para los proyectos 2024 el plazo para presentar informaci\u00f3n en la delegaci\u00f3n departamental de SEGEPLAN se venci\u00f3 el 15 de noviembre, en este momento despu\u00e9s de esta fecha hasta el 29 de ese mismo mes tienen el tiempo para la revisi\u00f3n de la documentaci\u00f3n, seg\u00fan el Ing. Manuel C\u00e1rcamo delegado interino de SEGEPLAN. MIRA: Presentan la 2da. edici\u00f3n de la revista inform\u00e1tica sobre el empleo y desempleo El sistema se cierra este viernes, ya que es el \u00faltimo d\u00eda h\u00e1bil del mes de noviembre, posterior a esta fecha deben esperar&hellip;<\/p>\n","protected":false},"author":2,"featured_media":22236,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[7891,7890],"class_list":["post-22246","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales","tag-de-los-documentos-de-proyectos-2024","tag-tiene-hasta-este-viernes-para-la-revision"],"gutentor_comment":0,"_links":{"self":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts\/22246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/comments?post=22246"}],"version-history":[{"count":2,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts\/22246\/revisions"}],"predecessor-version":[{"id":22252,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts\/22246\/revisions\/22252"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/media\/22236"}],"wp:attachment":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/media?parent=22246"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/categories?post=22246"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/tags?post=22246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}