{"id":2167,"date":"2021-12-21T13:09:15","date_gmt":"2021-12-21T13:09:15","guid":{"rendered":"https:\/\/www.notijalapa.net\/noticias\/?p=2167"},"modified":"2021-12-21T13:24:55","modified_gmt":"2021-12-21T13:24:55","slug":"en-46-horas-realizaron-el-reto-everesting-en-jalapa","status":"publish","type":"post","link":"https:\/\/www.notijalapa.net\/noticias\/2021\/12\/21\/en-46-horas-realizaron-el-reto-everesting-en-jalapa\/","title":{"rendered":"En 46 horas realizaron el reto Everesting en Jalapa"},"content":{"rendered":"<p>El pasado fin de semana se realiz\u00f3 el Everesting, el cual dio inicio el d\u00eda viernes a las 7:00 horas y finalizo el d\u00eda domingo a las 5:00 horas, con mucho nerviosismos porque estaban a la expectativa de que cualquier cosa pod\u00eda pasar, porque siempre hay muchos factores que no est\u00e1n en las manos de los organizadores, como el clima, lesiones, golpes, ataque de alg\u00fan animal, entre otras cosas, pero despu\u00e9s de 46 horas terminaron el reto, seg\u00fan lo dio a conocer Kimberly Cristabel Corredora de Monta\u00f1a.<\/p>\n<p><a href=\"https:\/\/www.notijalapa.net\/noticias\/2021\/12\/21\/culminan-actividades-en-escuela-de-montanismo\/\">MIRA: Culminan actividades en escuela de monta\u00f1ismo<\/a><\/p>\n<p>Seg\u00fan Mario El\u00edas escalador de Monta\u00f1a, este reto lo iniciaron tres, siendo ellos Kimberly Cristabel, Mario El\u00edas y Alberto Lucas, pero lamentablemente en los descensos del volc\u00e1n hay demasiado impacto y el compa\u00f1ero Alberto en el s\u00e9ptimo descenso se le inflamo mucho la rodilla y ya no pudo terminarlo.<\/p>\n<p><iframe loading=\"lazy\" title=\"En 46 Horas Realizaron El Reto Everesting En Jalapa 1\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/PrbQ_jYliXI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>Este reto del Everestign lo realizaron en el volv\u00edan Jumay, dicho reto consist\u00eda en igualar la altura del Everest que tienen 8,848 metros sobre el nivel del mar, por ello tuvieron que subir 13 veces el volc\u00e1n Jumay para igual la altura, despu\u00e9s al hacer cuenta y sumar los metros, pudieron determinar que eran 12 asensos al volc\u00e1n los que necesitaban, eso quiere decir que hicieron un acenso m\u00e1s, por lo tanto, la meta que se hab\u00edan propuesta la superaron.<\/p>\n<p>Cabe mencionar que al iniciar este reto no pueden dormir, tienen que seguir subiendo y bajando el volc\u00e1n hasta cumplir con los 8,848 metros, ellos lo hicieron en 46 horas, y agradecen a todas las personas que los apoyaron en la log\u00edstica, en la alimentaci\u00f3n, en la seguridad y en apoyarlos moral y psicol\u00f3gicamente.<\/p>\n<p>Agradecen tambi\u00e9n a todas las personas que de una u otra forma los apoyaron, tanto econ\u00f3micamente, como en alimentos e hidrataci\u00f3n, y este logro ambos atletas se lo dedican a sus familias.<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2Fpermalink.php%3Fstory_fbid%3D4690643371051777%26id%3D541551329294356&amp;show_text=true&amp;width=500\" width=\"500\" height=\"754\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado fin de semana se realiz\u00f3 el Everesting, el cual dio inicio el d\u00eda viernes a las 7:00 horas y finalizo el d\u00eda domingo a las 5:00 horas, con mucho nerviosismos porque estaban a la expectativa de que cualquier cosa pod\u00eda pasar, porque siempre hay muchos factores que no est\u00e1n en las manos de los organizadores, como el clima, lesiones, golpes, ataque de alg\u00fan animal, entre otras cosas, pero despu\u00e9s de 46 horas terminaron el reto, seg\u00fan lo dio a conocer Kimberly Cristabel Corredora de Monta\u00f1a. MIRA: Culminan actividades&hellip;<\/p>\n","protected":false},"author":2,"featured_media":2160,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[395,393,394],"class_list":["post-2167","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales","tag-46-horas-terminaron-el-reto","tag-everesting","tag-volcan-jumay"],"gutentor_comment":0,"_links":{"self":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts\/2167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/comments?post=2167"}],"version-history":[{"count":2,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts\/2167\/revisions"}],"predecessor-version":[{"id":2173,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts\/2167\/revisions\/2173"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/media\/2160"}],"wp:attachment":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/media?parent=2167"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/categories?post=2167"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/tags?post=2167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}