{"id":20122,"date":"2024-07-25T11:14:46","date_gmt":"2024-07-25T11:14:46","guid":{"rendered":"https:\/\/www.notijalapa.net\/noticias\/?p=20122"},"modified":"2024-07-25T11:25:11","modified_gmt":"2024-07-25T11:25:11","slug":"no-tienen-personal-para-evaluar-la-calidad-de-los-materiales-de-los-proyectos","status":"publish","type":"post","link":"https:\/\/www.notijalapa.net\/noticias\/2024\/07\/25\/no-tienen-personal-para-evaluar-la-calidad-de-los-materiales-de-los-proyectos\/","title":{"rendered":"No tienen personal para evaluar la calidad de los materiales de los proyectos"},"content":{"rendered":"<p>Como Consejos de Desarrollo cuentan con dos personas quienes son los responsables de realizar los monitoreos de la ejecuci\u00f3n de obras, quienes deben darles la seguridad que los proyectos est\u00e1n caminando de buena manera, pero no cuentan con las herramientas necesarias como investigaci\u00f3n de la calidad de los materiales, sino que se dedican m\u00e1s que todo a ver avances de los proyectos, seg\u00fan lo manifest\u00f3 el Lic. Eddy Ju\u00e1rez director ejecutivo de CODEDE.<\/p>\n<p><a href=\"https:\/\/www.notijalapa.net\/noticias\/2024\/07\/25\/esperan-que-terminen-las-adecuaciones-para-hacer-el-traslado-del-cemucaf\/\">MIRA: Esperan que terminen las adecuaciones para hacer el traslado del CEMUCAF<\/a><\/p>\n<p>Lamentablemente el revisar consistencia, compactaciones y la calidad de los proyectos no tienen la capacidad de evaluarla, sino que son las municipalidades las que tendr\u00edan que hacerlo a trav\u00e9s de sus supervisores los an\u00e1lisis y hacer proyectos de buena calidad.<\/p>\n<p><iframe loading=\"lazy\" title=\"No tienen personal para evaluar la calidad de los materiales de los proyectos\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/0nTRp2cjlTw?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>Los COCODES est\u00e1n con todo el derecho de argumentar, indicar que si ven algo que nos les gusta denunciarlo y si no es el proyecto que ellos pidieron tambi\u00e9n est\u00e1n en el derecho de indicarlo, porque son ellos los que deber\u00edan de ejercer la auditoria social, para que los proyectos sean de buena calidad.<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2Fpermalink.php%3Fstory_fbid%3Dpfbid023gFp7o9pZwT5TJhsfsXQ7hDhkqS3YTdBsvVxHoFgb8YG4ngWKcB79feLfQGjBCe4l%26id%3D100083158940816&amp;show_text=true&amp;width=500\" width=\"500\" height=\"793\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como Consejos de Desarrollo cuentan con dos personas quienes son los responsables de realizar los monitoreos de la ejecuci\u00f3n de obras, quienes deben darles la seguridad que los proyectos est\u00e1n caminando de buena manera, pero no cuentan con las herramientas necesarias como investigaci\u00f3n de la calidad de los materiales, sino que se dedican m\u00e1s que todo a ver avances de los proyectos, seg\u00fan lo manifest\u00f3 el Lic. Eddy Ju\u00e1rez director ejecutivo de CODEDE. MIRA: Esperan que terminen las adecuaciones para hacer el traslado del CEMUCAF Lamentablemente el revisar consistencia, compactaciones&hellip;<\/p>\n","protected":false},"author":2,"featured_media":20111,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[6969,6968],"class_list":["post-20122","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales","tag-de-los-materiales-de-los-proyectos","tag-no-tienen-personal-para-evaluar-la-calidad"],"gutentor_comment":0,"_links":{"self":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts\/20122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/comments?post=20122"}],"version-history":[{"count":2,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts\/20122\/revisions"}],"predecessor-version":[{"id":20128,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts\/20122\/revisions\/20128"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/media\/20111"}],"wp:attachment":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/media?parent=20122"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/categories?post=20122"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/tags?post=20122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}