{"id":19628,"date":"2024-06-26T10:53:30","date_gmt":"2024-06-26T10:53:30","guid":{"rendered":"https:\/\/www.notijalapa.net\/noticias\/?p=19628"},"modified":"2024-06-26T11:03:22","modified_gmt":"2024-06-26T11:03:22","slug":"inundaciones-se-dan-por-las-topografias-de-los-terrenos","status":"publish","type":"post","link":"https:\/\/www.notijalapa.net\/noticias\/2024\/06\/26\/inundaciones-se-dan-por-las-topografias-de-los-terrenos\/","title":{"rendered":"Inundaciones se dan por las topograf\u00edas de los terrenos"},"content":{"rendered":"<p>Si hacemos un an\u00e1lisis global de las lluvias del pasado fin de semana, todo el departamento como tal gener\u00f3 mucha presencia de lluvias a escala moderada, porque las aguas que generaron en el suelo se convirtieron en r\u00edos, seg\u00fan lo dio a conocer el Lic. Virgilio \u00c1lvaro Ram\u00edrez delegado de la CONRED.<\/p>\n<p><a href=\"https:\/\/www.notijalapa.net\/noticias\/2024\/06\/26\/procesos-se-atrasarian-porque-los-reos-podrian-ser-trasladados-a-otro-lugar\/\">MIRA: Procesos se atrasar\u00edan porque los reos podr\u00edan ser trasladados a otro lugar<\/a><\/p>\n<p>Jalapa tiene tres sectores que se inundan, pero no son porque los drenajes no se den abasto, sino que es por la topograf\u00eda del lugar que hace que el lugar quede en un nivel sin salida, para ello se necesita del apoyo de bombas y pipas para succionar esa agua.<\/p>\n<p><iframe loading=\"lazy\" title=\"Inundaciones se dan por las topograf\u00edas de los terrenos\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/OYxiZaUpN1s?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>Analizando lo ocurrido en el hospital sobre la inundaci\u00f3n, es el lugar que no es el adecuado, los tragantes est\u00e1n bien y no ten\u00edan mucha basura, pero por la magnitud de agua que cay\u00f3 hizo que las calles se convirtieran en r\u00edos con un nivel de casi un metro y eso sobrepaso el nivel de la entrada al hospital.<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2Fpermalink.php%3Fstory_fbid%3Dpfbid02xnHvphdoUKwTfYMbGuN9uVBNEJ64no7wGJwej831dGHmkBFGDrGSG8kZe8wtSJqal%26id%3D100083158940816&amp;show_text=true&amp;width=500\" width=\"500\" height=\"794\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si hacemos un an\u00e1lisis global de las lluvias del pasado fin de semana, todo el departamento como tal gener\u00f3 mucha presencia de lluvias a escala moderada, porque las aguas que generaron en el suelo se convirtieron en r\u00edos, seg\u00fan lo dio a conocer el Lic. Virgilio \u00c1lvaro Ram\u00edrez delegado de la CONRED. MIRA: Procesos se atrasar\u00edan porque los reos podr\u00edan ser trasladados a otro lugar Jalapa tiene tres sectores que se inundan, pero no son porque los drenajes no se den abasto, sino que es por la topograf\u00eda del lugar&hellip;<\/p>\n","protected":false},"author":2,"featured_media":19618,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[6750,6751],"class_list":["post-19628","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales","tag-inundaciones-se-dan-por-las","tag-topografias-de-los-terrenos"],"gutentor_comment":0,"_links":{"self":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts\/19628","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/comments?post=19628"}],"version-history":[{"count":2,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts\/19628\/revisions"}],"predecessor-version":[{"id":19635,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts\/19628\/revisions\/19635"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/media\/19618"}],"wp:attachment":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/media?parent=19628"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/categories?post=19628"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/tags?post=19628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}