{"id":1737,"date":"2021-11-27T13:11:12","date_gmt":"2021-11-27T13:11:12","guid":{"rendered":"https:\/\/www.notijalapa.net\/noticias\/?p=1737"},"modified":"2021-11-27T13:30:06","modified_gmt":"2021-11-27T13:30:06","slug":"en-las-ultimas-horas-seis-personas-dieron-positivo-para-covid-19-en-jalapa","status":"publish","type":"post","link":"https:\/\/www.notijalapa.net\/noticias\/2021\/11\/27\/en-las-ultimas-horas-seis-personas-dieron-positivo-para-covid-19-en-jalapa\/","title":{"rendered":"En las \u00faltimas horas seis personas dieron positivo para Covid-19 en Jalapa"},"content":{"rendered":"<p>Seg\u00fan el reporte de casos positivos en el departamento de Jalapa, por parte del Ministerio de Salud P\u00fablica y Asistencia Social durante las \u00faltimas 24 horas, se reportaron 6 casos positivos, de los cuales tres son del municipio de Jalapa, dos de Mataquescuintla y uno de Monjas, seg\u00fan lo dio a conocer la Licda. Magda Casta\u00f1eda del \u00c1rea de Salud de Jalapa. Cada d\u00eda de esta semana estuvieron reportando entre 1 a 6 contagiados del Covid-19.<\/p>\n<p><a href=\"https:\/\/www.notijalapa.net\/noticias\/2021\/11\/27\/talas-de-arboles-ilegales-han-aumentado\/\">MIRA: Talas de \u00e1rboles ilegales han aumentado<\/a><\/p>\n<p>Seg\u00fan el consolidado de casos positivos desde que inicio la pandemia a la fecha se han registrado 7,533, de los cuales 4,110 son de Jalapa, 696 de San Pedro Pinula, 835 de San Luis Jilotepeque, 731 de Mataquescuintla, 318 de San Manuel Chaparr\u00f3n, 705 de Monjas y 138 de San Carlos Alzatate.<\/p>\n<p><iframe loading=\"lazy\" title=\"En Las \u00daltimas Horas Seis Personas Dieron Positivo Para Covid 19 En Jalapa 1\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/NR-A5k3AzKM?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>Hasta el momento 7,276 personas se han recuperado de Covid-19 en el departamento de Jalapa, y actualmente hay 120 personas que se encuentran a\u00fan positivas y se ha registrado el fallecimiento de 137 jalapanecos a causa del Covid-19.<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2Fpermalink.php%3Fstory_fbid%3D4601786076604174%26id%3D541551329294356&amp;show_text=true&amp;width=500\" width=\"500\" height=\"812\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seg\u00fan el reporte de casos positivos en el departamento de Jalapa, por parte del Ministerio de Salud P\u00fablica y Asistencia Social durante las \u00faltimas 24 horas, se reportaron 6 casos positivos, de los cuales tres son del municipio de Jalapa, dos de Mataquescuintla y uno de Monjas, seg\u00fan lo dio a conocer la Licda. Magda Casta\u00f1eda del \u00c1rea de Salud de Jalapa. Cada d\u00eda de esta semana estuvieron reportando entre 1 a 6 contagiados del Covid-19. MIRA: Talas de \u00e1rboles ilegales han aumentado Seg\u00fan el consolidado de casos positivos desde&hellip;<\/p>\n","protected":false},"author":2,"featured_media":1738,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[26,198],"class_list":["post-1737","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales","tag-covid-19","tag-ministerio-de-salud-publica-y-asistencia-social"],"gutentor_comment":0,"_links":{"self":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts\/1737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/comments?post=1737"}],"version-history":[{"count":2,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts\/1737\/revisions"}],"predecessor-version":[{"id":1757,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts\/1737\/revisions\/1757"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/media\/1738"}],"wp:attachment":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/media?parent=1737"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/categories?post=1737"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/tags?post=1737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}