{"id":16495,"date":"2023-12-16T12:46:32","date_gmt":"2023-12-16T12:46:32","guid":{"rendered":"https:\/\/www.notijalapa.net\/noticias\/?p=16495"},"modified":"2023-12-16T12:54:13","modified_gmt":"2023-12-16T12:54:13","slug":"de-no-renovar-los-contratos-manifestaran-sea-quien-sea-el-director-de-area-de-salud","status":"publish","type":"post","link":"https:\/\/www.notijalapa.net\/noticias\/2023\/12\/16\/de-no-renovar-los-contratos-manifestaran-sea-quien-sea-el-director-de-area-de-salud\/","title":{"rendered":"De no renovar los contratos manifestaran sea quien sea el director de \u00e1rea de salud"},"content":{"rendered":"<p>Como sindicato de salud, tuvieron una muy buena comunicaci\u00f3n con el Dr. Rafael Campos cuando era director del \u00e1rea de salud, saben que es una persona que tiene el t\u00edtulo de m\u00e9dico y tambi\u00e9n de licenciado, por ello conoce de leyes, pese a eso le hicieron varias manifestaciones, seg\u00fan lo dio a conocer Am\u00edlcar Alay secretario general del Sindicato Frente Nacional de Lucha.<\/p>\n<p><a href=\"https:\/\/www.notijalapa.net\/noticias\/2023\/12\/16\/no-a-los-disparos-al-aire\/\">MIRA:No a los disparos al aire<\/a><\/p>\n<p>Siempre que ten\u00edan algunos inconvenientes se reun\u00edan con el doctor Campos en juntas mixtas para resolver esos problemas, pero cuando no llegaban a los acuerdos pertinentes, tambi\u00e9n tomaban las medidas de hecho, una de ellas era el manifestar frente a las instalaciones del \u00e1rea de salud.<\/p>\n<p><iframe loading=\"lazy\" title=\"De no renovar los contratos manifestaran sea quien sea el director de \u00e1rea de salud\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/n8vNBnibf3s?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>Lo mismo van hacer con el actual director del \u00e1rea de salud, debido que al iniciar el a\u00f1o 2024 quieren ver que se contraten a todos los trabajadores que est\u00e1n por contrato, debido que el Congreso de la Republica les aprobado 300 millones para darle continuidad a crear las plazas que las personas que est\u00e1n por contrato y pasarlos a 011, tambi\u00e9n viene incluido el aumento para el 2024 y el a\u00f1o 2025.<\/p>\n<p>Ya tienen instrucciones que se dieron a nivel nacional a trav\u00e9s de la asamblea del comit\u00e9 ejecutivo de sacar el listado de las personas que no contrataron. Si hay justificaciones de personas que no cumplen con sus obligaciones y las normas de ser un buen trabajador no meten las manos por ellos, pero si hay injusticias si van a tomar medidas a partir del 02 de enero este o no el Dr. Juan Carlos Rodr\u00edguez como director.<\/p>\n<p>Sabemos que, en enero se da el cambio de autoridades y todo director a nivel nacional va hacer el sindicato el que va decidir a qui\u00e9n quiere de director, con el objetivo de trabajar en conjunto en beneficio de los trabajares de salud, puntualizo Alay.<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2Fpermalink.php%3Fstory_fbid%3Dpfbid029HMo4M7Vu16A2u9APX4qEKMJV2aMBPB5WCScvpjXy5mNr9ZeFfU9aMwtLG71TaKWl%26id%3D100083158940816&amp;show_text=true&amp;width=500\" width=\"500\" height=\"545\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como sindicato de salud, tuvieron una muy buena comunicaci\u00f3n con el Dr. Rafael Campos cuando era director del \u00e1rea de salud, saben que es una persona que tiene el t\u00edtulo de m\u00e9dico y tambi\u00e9n de licenciado, por ello conoce de leyes, pese a eso le hicieron varias manifestaciones, seg\u00fan lo dio a conocer Am\u00edlcar Alay secretario general del Sindicato Frente Nacional de Lucha. MIRA:No a los disparos al aire Siempre que ten\u00edan algunos inconvenientes se reun\u00edan con el doctor Campos en juntas mixtas para resolver esos problemas, pero cuando no&hellip;<\/p>\n","protected":false},"author":2,"featured_media":16484,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[5400,5401],"class_list":["post-16495","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales","tag-de-no-renovar-los-contratos-manifestaran","tag-sea-quien-sea-el-director-de-area-de-salud"],"gutentor_comment":0,"_links":{"self":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts\/16495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/comments?post=16495"}],"version-history":[{"count":3,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts\/16495\/revisions"}],"predecessor-version":[{"id":16498,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts\/16495\/revisions\/16498"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/media\/16484"}],"wp:attachment":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/media?parent=16495"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/categories?post=16495"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/tags?post=16495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}