{"id":14796,"date":"2023-08-31T12:36:38","date_gmt":"2023-08-31T12:36:38","guid":{"rendered":"https:\/\/www.notijalapa.net\/noticias\/?p=14796"},"modified":"2023-08-31T12:46:37","modified_gmt":"2023-08-31T12:46:37","slug":"hay-demasiada-inseguridad-para-los-jalapanecos","status":"publish","type":"post","link":"https:\/\/www.notijalapa.net\/noticias\/2023\/08\/31\/hay-demasiada-inseguridad-para-los-jalapanecos\/","title":{"rendered":"Hay demasiada inseguridad para los jalapanecos"},"content":{"rendered":"<p>Esperan que la seguridad mejore en el departamento de Jalapa, y que las muertes violentas en contra de cualquier persona ya no se den, que el Gobernador de Jalapa implemente planes, programas y proyectos a favor de erradicar la violencia, seg\u00fan lo dio a conocer la Licda. Cecilia Isabel Aguirre Auxiliar del Procurador de los Derechos Humanos.<\/p>\n<p><a href=\"https:\/\/www.notijalapa.net\/noticias\/2023\/08\/31\/trabajan-en-combatir-las-enfermedades-producidas-por-los-zancudos\/\">MIRA: Trabajan en combatir las enfermedades producidas por los zancudos<\/a><\/p>\n<p>Lamentablemente en los \u00faltimos d\u00edas se ha tenido un alza en el tema de las muertes violentas en el departamento de Jalapa, han visto que en la investigaci\u00f3n penal tampoco avanza y que de alguna manera est\u00e1n protegidos, lamentablemente en el departamento de Jalapa un policial debe de resguardar a m\u00e1s de mil ciudadanos y es imposible.<\/p>\n<p><iframe loading=\"lazy\" title=\"Hay demasiada inseguridad para los jalapanecos\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/WlfiWssOIA8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>Esperan que se tomen cartas en el asunto, porque las muertes violentas, asaltos y robos cada vez son m\u00e1s, y los jalapanecos est\u00e1n cansados de tanta inseguridad que se tiene en el departamento.<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2Fpermalink.php%3Fstory_fbid%3Dpfbid0JVfYEjsxFwfc9wAkiKaTNiYLciGynR4aosMtRf7YoqasFfRWVwzUgzgLsf124U2El%26id%3D100083158940816&amp;show_text=true&amp;width=500\" width=\"500\" height=\"506\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esperan que la seguridad mejore en el departamento de Jalapa, y que las muertes violentas en contra de cualquier persona ya no se den, que el Gobernador de Jalapa implemente planes, programas y proyectos a favor de erradicar la violencia, seg\u00fan lo dio a conocer la Licda. Cecilia Isabel Aguirre Auxiliar del Procurador de los Derechos Humanos. MIRA: Trabajan en combatir las enfermedades producidas por los zancudos Lamentablemente en los \u00faltimos d\u00edas se ha tenido un alza en el tema de las muertes violentas en el departamento de Jalapa, han&hellip;<\/p>\n","protected":false},"author":2,"featured_media":14787,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[4675,4676],"class_list":["post-14796","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales","tag-hay-demasiada-inseguridad","tag-para-los-jalapanecos"],"gutentor_comment":0,"_links":{"self":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts\/14796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/comments?post=14796"}],"version-history":[{"count":2,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts\/14796\/revisions"}],"predecessor-version":[{"id":14805,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts\/14796\/revisions\/14805"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/media\/14787"}],"wp:attachment":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/media?parent=14796"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/categories?post=14796"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/tags?post=14796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}