{"id":14423,"date":"2023-08-09T12:32:41","date_gmt":"2023-08-09T12:32:41","guid":{"rendered":"https:\/\/www.notijalapa.net\/noticias\/?p=14423"},"modified":"2023-08-09T12:44:11","modified_gmt":"2023-08-09T12:44:11","slug":"varios-sectores-sin-agua-por-una-fuga","status":"publish","type":"post","link":"https:\/\/www.notijalapa.net\/noticias\/2023\/08\/09\/varios-sectores-sin-agua-por-una-fuga\/","title":{"rendered":"Varios sectores sin agua por una fuga"},"content":{"rendered":"<p>Debido a una fuga que se tenia en la 2da. avenida y 6ta. calle en la zona 2 de Jalapa, tuvieron que suspender el servicio de agua potable del barrio Chipilapa, San Francisco, El Provenir, entre otros, seg\u00fan lo dio a conocer Geodany Escobar Gerente de Jalapagua.<\/p>\n<p><a href=\"https:\/\/www.notijalapa.net\/noticias\/2023\/08\/09\/lanzan-programa-agentes-de-cambio-para-ayudar-a-disminuir-la-desnutricion\/\">MIRA: Lanzan programa agentes de cambio para ayudar a disminuir la desnutrici\u00f3n<\/a><\/p>\n<p>La mayor cantidad de agua que abastecer los sectores antes mencionados son de la planta central y los pozos mec\u00e1nicos, pero para no tener presencia de agua en la reparaci\u00f3n que iban hacer tuvieron que apagarlos la mayor\u00eda de las fuentes, por ello varias viviendas se quedaron sin el servicio de vital l\u00edquido el d\u00eda lunes.<\/p>\n<p><iframe loading=\"lazy\" title=\"Varios sectores sin agua por una fuga\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/7FkIn1KaXJM?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>Para este martes ya fue activada la planta central de agua y los pozos mec\u00e1nicos que abastecen del vital liquido a los sectores, pero por todo el mecanismo no llegaran con mucha presi\u00f3n hasta el d\u00eda mi\u00e9rcoles, esperan la compresi\u00f3n de todas las personas, puntualizo.<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2Fpermalink.php%3Fstory_fbid%3Dpfbid02iSNFTazvnj345agWm5mAS5qPTKppYD1nGyQ2FJKoi3oxtCqQxoAfu2svszqAJ447l%26id%3D100083158940816&amp;show_text=true&amp;width=500\" width=\"500\" height=\"774\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Debido a una fuga que se tenia en la 2da. avenida y 6ta. calle en la zona 2 de Jalapa, tuvieron que suspender el servicio de agua potable del barrio Chipilapa, San Francisco, El Provenir, entre otros, seg\u00fan lo dio a conocer Geodany Escobar Gerente de Jalapagua. MIRA: Lanzan programa agentes de cambio para ayudar a disminuir la desnutrici\u00f3n La mayor cantidad de agua que abastecer los sectores antes mencionados son de la planta central y los pozos mec\u00e1nicos, pero para no tener presencia de agua en la reparaci\u00f3n que&hellip;<\/p>\n","protected":false},"author":2,"featured_media":14417,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[4515,4514],"class_list":["post-14423","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales","tag-por-una-fuga","tag-varios-sectores-sin-agua"],"gutentor_comment":0,"_links":{"self":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts\/14423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/comments?post=14423"}],"version-history":[{"count":2,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts\/14423\/revisions"}],"predecessor-version":[{"id":14435,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts\/14423\/revisions\/14435"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/media\/14417"}],"wp:attachment":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/media?parent=14423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/categories?post=14423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/tags?post=14423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}