{"id":12772,"date":"2023-05-20T12:51:05","date_gmt":"2023-05-20T12:51:05","guid":{"rendered":"https:\/\/www.notijalapa.net\/noticias\/?p=12772"},"modified":"2023-05-20T13:06:56","modified_gmt":"2023-05-20T13:06:56","slug":"aumentaran-los-trabajos-en-planta-central-para-la-distribucion-del-agua-potable","status":"publish","type":"post","link":"https:\/\/www.notijalapa.net\/noticias\/2023\/05\/20\/aumentaran-los-trabajos-en-planta-central-para-la-distribucion-del-agua-potable\/","title":{"rendered":"Aumentaran los trabajos en planta central para la distribuci\u00f3n del agua potable"},"content":{"rendered":"<p>Con la llegada del invierno, se espera que la recolecci\u00f3n de agua en la planta central sea mayor, aunque con ello los trabajos se tendr\u00e1n que intensificar al igual que el uso de los qu\u00edmicos para darle el debido tratamiento al agua, seg\u00fan lo dio a conocer Geodany Escobar gerente de Jalapagua.<\/p>\n<p><a href=\"http:\/\/notijalapa.net\/noticias\/2023\/05\/20\/el-invierno-podria-ingresar-la-proxima-semana\/\">MIRA: El invierno podr\u00eda ingresar la pr\u00f3xima semana<\/a><\/p>\n<p>Recordemos que, la planta central abastece un 70 por ciento del vital l\u00edquido a la poblaci\u00f3n jalapaneca, por ello es que el tratamiento debe de ser adecuado para evitar un foco de contaminaci\u00f3n, debido que aumenta el caudal del agua, pero esta llega m\u00e1s turbia.<\/p>\n<p><iframe loading=\"lazy\" title=\"Aumentaran los trabajos en planta central para la distribuci\u00f3n del agua potable\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/FkcxjTRAZxc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>Los pozos mec\u00e1nicos continuaran trabajando de la misma manera como han estado funcionando actualmente en el municipio de Jalapa, no hay ninguna variaci\u00f3n con el ingreso del inverno, puntualiz\u00f3.<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2Fpermalink.php%3Fstory_fbid%3Dpfbid0c9EUf8Njr5Ppg9YLgY18wkrTvpkMCuTt3fWjLycgJGnG1qq6HhDrdgWJpTz3cEfQl%26id%3D100083158940816&amp;show_text=true&amp;width=500\" width=\"500\" height=\"506\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con la llegada del invierno, se espera que la recolecci\u00f3n de agua en la planta central sea mayor, aunque con ello los trabajos se tendr\u00e1n que intensificar al igual que el uso de los qu\u00edmicos para darle el debido tratamiento al agua, seg\u00fan lo dio a conocer Geodany Escobar gerente de Jalapagua. MIRA: El invierno podr\u00eda ingresar la pr\u00f3xima semana Recordemos que, la planta central abastece un 70 por ciento del vital l\u00edquido a la poblaci\u00f3n jalapaneca, por ello es que el tratamiento debe de ser adecuado para evitar un&hellip;<\/p>\n","protected":false},"author":2,"featured_media":12764,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[3925,3926],"class_list":["post-12772","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales","tag-aumentaran-los-trabajos-en-planta-central","tag-para-la-distribucion-del-agua-potable"],"gutentor_comment":0,"_links":{"self":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts\/12772","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/comments?post=12772"}],"version-history":[{"count":2,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts\/12772\/revisions"}],"predecessor-version":[{"id":12781,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/posts\/12772\/revisions\/12781"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/media\/12764"}],"wp:attachment":[{"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/media?parent=12772"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/categories?post=12772"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notijalapa.net\/noticias\/wp-json\/wp\/v2\/tags?post=12772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}